{"id":683387,"count":1,"description":"","link":"https:\/\/siddhivinayakholidays.co.in\/kashmir\/tag\/trip-to-kashmir-in-march-from-south-khasi-hills\/","name":"trip to kashmir in march from South Khasi Hills","slug":"trip-to-kashmir-in-march-from-south-khasi-hills","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>trip to kashmir in march from South Khasi Hills Archives - SIDDHIVINAYAK TOURS &amp; TRAVELS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/siddhivinayakholidays.co.in\/kashmir\/tag\/trip-to-kashmir-in-march-from-south-khasi-hills\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"trip to kashmir in march from South Khasi Hills Archives - SIDDHIVINAYAK TOURS &amp; TRAVELS\" \/>\n<meta property=\"og:url\" content=\"https:\/\/siddhivinayakholidays.co.in\/kashmir\/tag\/trip-to-kashmir-in-march-from-south-khasi-hills\/\" \/>\n<meta property=\"og:site_name\" content=\"SIDDHIVINAYAK TOURS &amp; TRAVELS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/siddhivinayakholidays.co.in\\\/kashmir\\\/tag\\\/trip-to-kashmir-in-march-from-south-khasi-hills\\\/\",\"url\":\"https:\\\/\\\/siddhivinayakholidays.co.in\\\/kashmir\\\/tag\\\/trip-to-kashmir-in-march-from-south-khasi-hills\\\/\",\"name\":\"trip to kashmir in march from South Khasi Hills Archives - SIDDHIVINAYAK TOURS &amp; TRAVELS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/siddhivinayakholidays.co.in\\\/kashmir\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/siddhivinayakholidays.co.in\\\/kashmir\\\/tag\\\/trip-to-kashmir-in-march-from-south-khasi-hills\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/siddhivinayakholidays.co.in\\\/kashmir\\\/tag\\\/trip-to-kashmir-in-march-from-south-khasi-hills\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/siddhivinayakholidays.co.in\\\/kashmir\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"trip to kashmir in march from South Khasi Hills\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/siddhivinayakholidays.co.in\\\/kashmir\\\/#website\",\"url\":\"https:\\\/\\\/siddhivinayakholidays.co.in\\\/kashmir\\\/\",\"name\":\"SIDDHIVINAYAK TOURS & TRAVELS\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/siddhivinayakholidays.co.in\\\/kashmir\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/siddhivinayakholidays.co.in\\\/kashmir\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/siddhivinayakholidays.co.in\\\/kashmir\\\/#organization\",\"name\":\"SIDDHIVINAYAK TOURS & TRAVELS\",\"url\":\"https:\\\/\\\/siddhivinayakholidays.co.in\\\/kashmir\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/siddhivinayakholidays.co.in\\\/kashmir\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/siddhivinayakholidays.co.in\\\/kashmir\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/logo-1.png\",\"contentUrl\":\"https:\\\/\\\/siddhivinayakholidays.co.in\\\/kashmir\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/logo-1.png\",\"width\":1600,\"height\":323,\"caption\":\"SIDDHIVINAYAK TOURS & TRAVELS\"},\"image\":{\"@id\":\"https:\\\/\\\/siddhivinayakholidays.co.in\\\/kashmir\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"trip to kashmir in march from South Khasi Hills Archives - SIDDHIVINAYAK TOURS &amp; TRAVELS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/siddhivinayakholidays.co.in\/kashmir\/tag\/trip-to-kashmir-in-march-from-south-khasi-hills\/","og_locale":"en_US","og_type":"article","og_title":"trip to kashmir in march from South Khasi Hills Archives - SIDDHIVINAYAK TOURS &amp; TRAVELS","og_url":"https:\/\/siddhivinayakholidays.co.in\/kashmir\/tag\/trip-to-kashmir-in-march-from-south-khasi-hills\/","og_site_name":"SIDDHIVINAYAK TOURS &amp; TRAVELS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/siddhivinayakholidays.co.in\/kashmir\/tag\/trip-to-kashmir-in-march-from-south-khasi-hills\/","url":"https:\/\/siddhivinayakholidays.co.in\/kashmir\/tag\/trip-to-kashmir-in-march-from-south-khasi-hills\/","name":"trip to kashmir in march from South Khasi Hills Archives - SIDDHIVINAYAK TOURS &amp; TRAVELS","isPartOf":{"@id":"https:\/\/siddhivinayakholidays.co.in\/kashmir\/#website"},"breadcrumb":{"@id":"https:\/\/siddhivinayakholidays.co.in\/kashmir\/tag\/trip-to-kashmir-in-march-from-south-khasi-hills\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/siddhivinayakholidays.co.in\/kashmir\/tag\/trip-to-kashmir-in-march-from-south-khasi-hills\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/siddhivinayakholidays.co.in\/kashmir\/"},{"@type":"ListItem","position":2,"name":"trip to kashmir in march from South Khasi Hills"}]},{"@type":"WebSite","@id":"https:\/\/siddhivinayakholidays.co.in\/kashmir\/#website","url":"https:\/\/siddhivinayakholidays.co.in\/kashmir\/","name":"SIDDHIVINAYAK TOURS & TRAVELS","description":"","publisher":{"@id":"https:\/\/siddhivinayakholidays.co.in\/kashmir\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/siddhivinayakholidays.co.in\/kashmir\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/siddhivinayakholidays.co.in\/kashmir\/#organization","name":"SIDDHIVINAYAK TOURS & TRAVELS","url":"https:\/\/siddhivinayakholidays.co.in\/kashmir\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/siddhivinayakholidays.co.in\/kashmir\/#\/schema\/logo\/image\/","url":"https:\/\/siddhivinayakholidays.co.in\/kashmir\/wp-content\/uploads\/2024\/06\/logo-1.png","contentUrl":"https:\/\/siddhivinayakholidays.co.in\/kashmir\/wp-content\/uploads\/2024\/06\/logo-1.png","width":1600,"height":323,"caption":"SIDDHIVINAYAK TOURS & TRAVELS"},"image":{"@id":"https:\/\/siddhivinayakholidays.co.in\/kashmir\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/siddhivinayakholidays.co.in\/kashmir\/wp-json\/wp\/v2\/tags\/683387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/siddhivinayakholidays.co.in\/kashmir\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/siddhivinayakholidays.co.in\/kashmir\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/siddhivinayakholidays.co.in\/kashmir\/wp-json\/wp\/v2\/posts?tags=683387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}